{"id":2,"date":"2025-02-11T06:32:46","date_gmt":"2025-02-11T06:32:46","guid":{"rendered":"https:\/\/bridgeindprod.wpenginepowered.com\/bridgepointporteverglades\/?page_id=2"},"modified":"2026-05-07T19:26:06","modified_gmt":"2026-05-07T19:26:06","slug":"sample-page","status":"publish","type":"page","link":"https:\/\/kurvindustrial.com\/kurvporteverglades\/","title":{"rendered":"Homepage"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;965&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; full_height=&#8221;yes&#8221; columns_placement=&#8221;bottom&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;7%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;7%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;custom&#8221; row_border_radius_applies=&#8221;both&#8221; bottom_right_border_radius=&#8221;50px&#8221; zindex=&#8221;100&#8243; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;hidden&#8221; advanced_gradient=&#8221;linear-gradient(45deg, rgb(7, 29, 71) 3%, rgba(7, 29, 71, 0) 55%)&#8221; advanced_gradient_angle=&#8221;45&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;zoom-out&#8221; mobile_disable_bg_image_animation=&#8221;true&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;advanced&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;static&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;100px&#8221; constrain_group_2=&#8221;yes&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; zindex=&#8221;10&#8243; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;New Class A Development<br \/>\nSoutheast Broward Submarket&#8221; font_container=&#8221;tag:h1|font_size:60px|text_align:left|line_height:55px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_custom_heading text=&#8221;Available for Immediate Occupancy&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;70px&#8221; bottom_padding=&#8221;20px&#8221; left_padding_desktop=&#8221;5vw&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5vw&#8221; top_padding_phone=&#8221;50px&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;50px&#8221; left_padding_phone=&#8221;5%&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;20px&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Kurv Port Everglades&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_video_lightbox link_style=&#8221;nectar-button&#8221; nectar_button_color=&#8221;Default-Accent-Color&#8221; link_text=&#8221;Play Video&#8221; video_url=&#8221;\/bridgepointporteverglades\/wp-content\/uploads\/sites\/7\/2025\/07\/Bridge-Point-Everglades-Movie-001.mp4&#8243;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;marg-left-10px&#8221; text=&#8221;Download Brochure&#8221; url=&#8221;\/bridgepointporteverglades\/wp-content\/uploads\/sites\/7\/2025\/07\/Bridge-Point-Everglades-Brochure-001.pdf&#8221; css_animation=&#8221;none&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;justify&#8221;]Ideally located just minutes from Port Everglades and Fort Lauderdale International Airport, Kurv Port Everglades delivers nearly 172,000 square feet of Class A industrial space in South Florida\u2019s most connected logistics hub. With 32\u2019 clear heights, dock-high loading, and immediate access to I-595, I-95, and Florida\u2019s Turnpike, this state-of-the-art facility is built for speed, efficiency, and scale.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0px&#8221; bottom_padding=&#8221;70px&#8221; left_padding_desktop=&#8221;5vw&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5vw&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;stats&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column left_padding_desktop=&#8221;20px&#8221; bottom_padding_phone=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;2px&#8221; border_left_phone=&#8221;0px&#8221; border_bottom_phone=&#8221;2px&#8221; column_border_color=&#8221;#0c59f2&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; offset=&#8221;vc_col-xs-6&#8243;][vc_custom_heading text=&#8221;171,983&#8243; font_container=&#8221;tag:h4|text_align:left|color:%23071D47&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Square Feet[\/vc_column_text][\/vc_column][vc_column left_padding_desktop=&#8221;20px&#8221; bottom_padding_phone=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;2px&#8221; border_left_phone=&#8221;0px&#8221; border_bottom_phone=&#8221;2px&#8221; column_border_color=&#8221;#0c59f2&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; offset=&#8221;vc_col-xs-6&#8243;][vc_custom_heading text=&#8221;22.4&#8243; font_container=&#8221;tag:h4|text_align:left|color:%23071D47&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Land Area (Acres)[\/vc_column_text][\/vc_column][vc_column left_padding_desktop=&#8221;20px&#8221; bottom_padding_phone=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;2px&#8221; border_left_phone=&#8221;0px&#8221; border_bottom_phone=&#8221;2px&#8221; column_border_color=&#8221;#0c59f2&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; offset=&#8221;vc_col-xs-6&#8243;][vc_custom_heading text=&#8221;Q2 2024&#8243; font_container=&#8221;tag:h4|text_align:left|color:%23071D47&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Completion Date[\/vc_column_text][\/vc_column][vc_column left_padding_desktop=&#8221;20px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;left&#8221; tablet_text_alignment=&#8221;center&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;slight-fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;2px&#8221; border_left_phone=&#8221;0px&#8221; border_bottom_phone=&#8221;2px&#8221; column_border_color=&#8221;#0C59F2&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-6&#8243;][vc_custom_heading text=&#8221;Submarket&#8221; font_container=&#8221;tag:h4|text_align:left|color:%23071D47&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]SE Broward[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;5px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin=&#8221;10px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;curved-box-section&#8221; advanced_gradient_angle=&#8221;9&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;slight-zoom-out-reveal&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;963&#8243; background_image_type=&#8221;default&#8221; background_image_position=&#8221;center center&#8221; background_image_stacking=&#8221;default&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;curved-corner&#8221; advanced_gradient=&#8221;linear-gradient(9deg, rgb(0,18,46) 11%, rgba(10,22,67,0) 53%)&#8221; advanced_gradient_angle=&#8221;9&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;zoom-out-reveal&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; column_link=&#8221;\/kurvporteverglades\/overview&#8221; gradient_type=&#8221;advanced&#8221; advanced_gradient_display_type=&#8221;linear&#8221; column_link_screen_reader=&#8221;Property Overview&#8221; content_layout=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;300px&#8221; bottom_padding=&#8221;7%&#8221; left_padding_desktop=&#8221;7%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;7%&#8221; top_padding_phone=&#8221;200px&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Property Overview&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; max_width=&#8221;500px&#8221; el_class=&#8221;justify&#8221;]Kurv Port Everglades is a state-of-the-art, high image distribution warehouse with frontage &amp; visibility.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;981&#8243; background_image_type=&#8221;default&#8221; background_image_position=&#8221;center center&#8221; background_image_stacking=&#8221;default&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;curved-corner&#8221; advanced_gradient=&#8221;linear-gradient(9deg, rgb(0,18,46) 13%, rgba(10,22,67,0) 54%)&#8221; advanced_gradient_angle=&#8221;9&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-right&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;zoom-out-reveal&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;advanced&#8221; advanced_gradient_display_type=&#8221;linear&#8221; column_link=&#8221;\/kurvporteverglades\/location&#8221; delay=&#8221;300&#8243; column_link_screen_reader=&#8221;Location &amp; Access&#8221; content_layout=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;300px&#8221; bottom_padding=&#8221;7%&#8221; left_padding_desktop=&#8221;7%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;7%&#8221; top_padding_phone=&#8221;200px&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Location &amp; Access&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; max_width=&#8221;500px&#8221; el_class=&#8221;justify&#8221;]South Florida\u2019s robust population and business friendly environment continue to incentivize capital migration.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin=&#8221;10px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;flickity_static_height_style&#8221; images=&#8221;966,972,965,981,963,962,979,973,978,975,982,974,964&#8243; flickity_spacing=&#8221;5px&#8221; flickity_controls=&#8221;next_prev_arrows_overlaid&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_image_scale_on_drag=&#8221;true&#8221; flickity_box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; onclick=&#8221;link_image&#8221; flickity_img_height=&#8221;600px&#8221; flickity_img_mobile_height=&#8221;300px&#8221; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;0px&#8221; top_margin=&#8221;0px&#8221; constrain_group_7=&#8221;yes&#8221; bottom_margin=&#8221;0px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;889&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;965&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; full_height=&#8221;yes&#8221; columns_placement=&#8221;bottom&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;7%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;7%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;custom&#8221; row_border_radius_applies=&#8221;both&#8221; bottom_right_border_radius=&#8221;50px&#8221; zindex=&#8221;100&#8243; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;hidden&#8221; advanced_gradient=&#8221;linear-gradient(45deg,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-2","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kurv Port Everglades - New Class A Development Southeast Broward Submarket<\/title>\n<meta name=\"description\" content=\"Kurv Port Everglades delivers nearly 172,000 square feet of Class A industrial space.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kurvindustrial.com\/kurvporteverglades\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kurv Port Everglades - New Class A Development Southeast Broward Submarket\" \/>\n<meta property=\"og:description\" content=\"Kurv Port Everglades delivers nearly 172,000 square feet of Class A industrial space.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kurvindustrial.com\/kurvporteverglades\/\" \/>\n<meta property=\"og:site_name\" content=\"Kurv Port Everglades\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T19:26:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kurvindustrial.com\\\/kurvporteverglades\\\/\",\"url\":\"https:\\\/\\\/kurvindustrial.com\\\/kurvporteverglades\\\/\",\"name\":\"Kurv Port Everglades - New Class A Development Southeast Broward Submarket\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kurvindustrial.com\\\/kurvporteverglades\\\/#website\"},\"datePublished\":\"2025-02-11T06:32:46+00:00\",\"dateModified\":\"2026-05-07T19:26:06+00:00\",\"description\":\"Kurv Port Everglades delivers nearly 172,000 square feet of Class A industrial space.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kurvindustrial.com\\\/kurvporteverglades\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kurvindustrial.com\\\/kurvporteverglades\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kurvindustrial.com\\\/kurvporteverglades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kurvindustrial.com\\\/kurvporteverglades\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homepage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kurvindustrial.com\\\/kurvporteverglades\\\/#website\",\"url\":\"https:\\\/\\\/kurvindustrial.com\\\/kurvporteverglades\\\/\",\"name\":\"Kurv Port Everglades\",\"description\":\"New Class A Development Southeast Broward Submarket\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kurvindustrial.com\\\/kurvporteverglades\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kurv Port Everglades - New Class A Development Southeast Broward Submarket","description":"Kurv Port Everglades delivers nearly 172,000 square feet of Class A industrial space.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kurvindustrial.com\/kurvporteverglades\/","og_locale":"en_US","og_type":"article","og_title":"Kurv Port Everglades - New Class A Development Southeast Broward Submarket","og_description":"Kurv Port Everglades delivers nearly 172,000 square feet of Class A industrial space.","og_url":"https:\/\/kurvindustrial.com\/kurvporteverglades\/","og_site_name":"Kurv Port Everglades","article_modified_time":"2026-05-07T19:26:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kurvindustrial.com\/kurvporteverglades\/","url":"https:\/\/kurvindustrial.com\/kurvporteverglades\/","name":"Kurv Port Everglades - New Class A Development Southeast Broward Submarket","isPartOf":{"@id":"https:\/\/kurvindustrial.com\/kurvporteverglades\/#website"},"datePublished":"2025-02-11T06:32:46+00:00","dateModified":"2026-05-07T19:26:06+00:00","description":"Kurv Port Everglades delivers nearly 172,000 square feet of Class A industrial space.","breadcrumb":{"@id":"https:\/\/kurvindustrial.com\/kurvporteverglades\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kurvindustrial.com\/kurvporteverglades\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kurvindustrial.com\/kurvporteverglades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kurvindustrial.com\/kurvporteverglades\/"},{"@type":"ListItem","position":2,"name":"Homepage"}]},{"@type":"WebSite","@id":"https:\/\/kurvindustrial.com\/kurvporteverglades\/#website","url":"https:\/\/kurvindustrial.com\/kurvporteverglades\/","name":"Kurv Port Everglades","description":"New Class A Development Southeast Broward Submarket","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kurvindustrial.com\/kurvporteverglades\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/kurvindustrial.com\/kurvporteverglades\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kurvindustrial.com\/kurvporteverglades\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kurvindustrial.com\/kurvporteverglades\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kurvindustrial.com\/kurvporteverglades\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kurvindustrial.com\/kurvporteverglades\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":0,"href":"https:\/\/kurvindustrial.com\/kurvporteverglades\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"wp:attachment":[{"href":"https:\/\/kurvindustrial.com\/kurvporteverglades\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}